
{"id":16607,"date":"2015-07-15T11:56:22","date_gmt":"2015-07-15T09:56:22","guid":{"rendered":"http:\/\/radiomoradebre.cat\/wp\/?p=16607"},"modified":"2015-07-15T11:56:22","modified_gmt":"2015-07-15T09:56:22","slug":"lasco-comenca-la-pretemporada","status":"publish","type":"post","link":"https:\/\/www.radiomoradebre.cat\/wp\/2015\/07\/15\/lasco-comenca-la-pretemporada\/","title":{"rendered":"L&#8217;Asc\u00f3 comen\u00e7a la pretemporada"},"content":{"rendered":"<p><em><strong>El Futbol Club Asc\u00f3 comen\u00e7a avui els entrenaments de temporada. L\u2019equip de Miguel Rubio conserva el gruix de jugadors de la temporada passada i ha refor\u00e7at, sobretot, el mig del camp. L\u2019Asc\u00f3 comen\u00e7ar\u00e0 la lliga comen\u00e7ar\u00e0 el proper 23 d\u2019agost amb l\u2019objectiu d\u2019acabar entre els quatre primers i tornar a competir al playoff d\u2019ascens. <\/strong><\/em><\/p>\n<p><em><strong>L&#8217;equip m\u00e9s matiner per\u00f2 va ser el Benissanet, que va comen\u00e7ar ahir els entrenaments amb quinze jugadors. L&#8217;entrenador, \u00c1lvaro Curto, vol confeccionar una plantilla jove i de futur per enfrontar amb garanties\u00a0la propera temporada a Quarta Catalana.<\/strong><\/em><\/p>\n<p>ANDREU PRUNERA \/ SISCO GRANELL<\/p>\n<p><a href=\"http:\/\/radiomoradebre.cat\/wp\/wp-content\/uploads\/2015\/07\/CRO-15-07-15-asco.mp3\">CRO 15-07-15 asco<\/a><\/p>\n<p><a href=\"http:\/\/radiomoradebre.cat\/wp\/wp-content\/uploads\/2015\/01\/asc.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-13129\" src=\"http:\/\/radiomoradebre.cat\/wp\/wp-content\/uploads\/2015\/01\/asc-300x133.jpg\" alt=\"asc\" width=\"300\" height=\"133\" srcset=\"https:\/\/www.radiomoradebre.cat\/wp\/wp-content\/uploads\/2015\/01\/asc-300x133.jpg 300w, https:\/\/www.radiomoradebre.cat\/wp\/wp-content\/uploads\/2015\/01\/asc.jpg 944w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Futbol Club Asc\u00f3 comen\u00e7a avui els entrenaments de temporada. L\u2019equip de Miguel Rubio conserva el gruix de jugadors de la temporada passada i ha refor\u00e7at, sobretot, el mig del camp. L\u2019Asc\u00f3 comen\u00e7ar\u00e0 la lliga comen\u00e7ar\u00e0 el proper 23 d\u2019agost &hellip; <a href=\"https:\/\/www.radiomoradebre.cat\/wp\/2015\/07\/15\/lasco-comenca-la-pretemporada\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[146,5083,1060,901,1265],"class_list":["post-16607","post","type-post","status-publish","format-standard","hentry","category-noticies","tag-benissanet","tag-competicio","tag-esports","tag-fc-asco","tag-futbol"],"_links":{"self":[{"href":"https:\/\/www.radiomoradebre.cat\/wp\/wp-json\/wp\/v2\/posts\/16607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiomoradebre.cat\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiomoradebre.cat\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiomoradebre.cat\/wp\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiomoradebre.cat\/wp\/wp-json\/wp\/v2\/comments?post=16607"}],"version-history":[{"count":1,"href":"https:\/\/www.radiomoradebre.cat\/wp\/wp-json\/wp\/v2\/posts\/16607\/revisions"}],"predecessor-version":[{"id":16609,"href":"https:\/\/www.radiomoradebre.cat\/wp\/wp-json\/wp\/v2\/posts\/16607\/revisions\/16609"}],"wp:attachment":[{"href":"https:\/\/www.radiomoradebre.cat\/wp\/wp-json\/wp\/v2\/media?parent=16607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiomoradebre.cat\/wp\/wp-json\/wp\/v2\/categories?post=16607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiomoradebre.cat\/wp\/wp-json\/wp\/v2\/tags?post=16607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}