
{"id":1517,"date":"2013-04-15T12:40:28","date_gmt":"2013-04-15T10:40:28","guid":{"rendered":"http:\/\/radiomoradebre.cat\/wp\/?p=1517"},"modified":"2013-04-15T12:40:28","modified_gmt":"2013-04-15T10:40:28","slug":"lajuntament-de-rasquera-demana-al-parlament-una-comissio-dexperts-per-plantacions-de-marihuana","status":"publish","type":"post","link":"https:\/\/www.radiomoradebre.cat\/wp\/2013\/04\/15\/lajuntament-de-rasquera-demana-al-parlament-una-comissio-dexperts-per-plantacions-de-marihuana\/","title":{"rendered":"L&#8217;Ajuntament de Rasquera demana al Parlament una comissi\u00f3 d&#8217;experts per plantacions de marihuana"},"content":{"rendered":"<p><em><strong>L&#8217;ajuntament de Rasquera demana a les inst\u00e0ncies judicials que resolguin els processos pendents que hi ha en relaci\u00f3 al projecte de la plantaci\u00f3 de marihuanna. Paral\u00b7lelament, tamb\u00e9 es vol traslladar el debat al Parlament.<\/strong><\/em><\/p>\n<p>L&#8217;alcalde, Bernat Pellissa, assegura que la q\u00fcesti\u00f3 s&#8217;ha polititzat i ha rebut moltes pressions per part de Fiscalia, que t\u00e9 dilig\u00e8ncies obertes des de fa un any. La iniciativa tamb\u00e9 continua aturada pel recurs estatal davant del jutjat contenci\u00f3s administratiu n\u00famero 1 de Tarragona.<\/p>\n<p><a href=\"http:\/\/radiomoradebre.cat\/wp\/wp-content\/uploads\/2013\/04\/BERNAT-PELLISA-15-4-INTIMIDAT.mp3\">BERNAT PELLISA 15-4 INTIMIDAT<\/a><\/p>\n<p>L&#8217;ajuntament ha aprovat en ple municipal una moci\u00f3 que demana al Parlament que cre\u00ef una comissi\u00f3 d&#8217;experts per analitzar els projectes de plantacions de marihuana, com el que impulsa aquest municipi Pellissa reitera que dimitir\u00e0 el proper 14 de juny. Ara fa un any es va comprometre a plegar si no aconseguia el 75% de dels vots ve\u00efnals en la consulta popular sobre el projecte, i els vots a favor no van arribar al 60%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;ajuntament de Rasquera demana a les inst\u00e0ncies judicials que resolguin els processos pendents que hi ha en relaci\u00f3 al projecte de la plantaci\u00f3 de marihuanna. Paral\u00b7lelament, tamb\u00e9 es vol traslladar el debat al Parlament. L&#8217;alcalde, Bernat Pellissa, assegura que la &hellip; <a href=\"https:\/\/www.radiomoradebre.cat\/wp\/2013\/04\/15\/lajuntament-de-rasquera-demana-al-parlament-una-comissio-dexperts-per-plantacions-de-marihuana\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[649,615,148],"class_list":["post-1517","post","type-post","status-publish","format-standard","hentry","category-noticies","tag-bernat-pellissa","tag-plantacio-marihuana","tag-rasquera"],"_links":{"self":[{"href":"https:\/\/www.radiomoradebre.cat\/wp\/wp-json\/wp\/v2\/posts\/1517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radiomoradebre.cat\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiomoradebre.cat\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiomoradebre.cat\/wp\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiomoradebre.cat\/wp\/wp-json\/wp\/v2\/comments?post=1517"}],"version-history":[{"count":2,"href":"https:\/\/www.radiomoradebre.cat\/wp\/wp-json\/wp\/v2\/posts\/1517\/revisions"}],"predecessor-version":[{"id":1521,"href":"https:\/\/www.radiomoradebre.cat\/wp\/wp-json\/wp\/v2\/posts\/1517\/revisions\/1521"}],"wp:attachment":[{"href":"https:\/\/www.radiomoradebre.cat\/wp\/wp-json\/wp\/v2\/media?parent=1517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiomoradebre.cat\/wp\/wp-json\/wp\/v2\/categories?post=1517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiomoradebre.cat\/wp\/wp-json\/wp\/v2\/tags?post=1517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}